{"id":1075,"date":"2010-06-24T16:02:02","date_gmt":"2010-06-24T14:02:02","guid":{"rendered":"http:\/\/achat.suisse-blog.ch\/?p=1075"},"modified":"2010-08-09T16:50:50","modified_gmt":"2010-08-09T14:50:50","slug":"shirtcity-ch-plus-de-1500-designs-pour-personnaliser-votre-t-shirt","status":"publish","type":"post","link":"https:\/\/achat.suisse-blog.ch\/de\/1075\/shirtcity-ch-plus-de-1500-designs-pour-personnaliser-votre-t-shirt\/","title":{"rendered":"Shirtcity.ch, plus de 1500 designs pour personnaliser votre t-shirt"},"content":{"rendered":"<p>Avec Shirtcity, vous pouvez cr\u00e9er votre propre t-shirt personnalis\u00e9 en y ajoutant votre photo, ou en faisant votre choix parmi une vaste gamme de motifs. En effet, peu importe le style que vous adoptez, vous y trouverez assur\u00e9ment un design qui vous plaira gr\u00e2ce aux quelque 1500 motifs propos\u00e9s par Shirtcity. R\u00e9pertori\u00e9s par cat\u00e9gories, les designs offerts portent aussi bien sur la politique, les fleurs, les enfants et les b\u00e9b\u00e9s, l\u2019amour, le mariage, les sports et loisirs, l\u2019humour, les animaux, l\u2019alcool, les t\u00eates de mort, etc. Plusieurs autres th\u00e8mes font \u00e9galement partie des motifs disponibles, dont ceux \u00e0 l\u2019effigie des villes et des pays, de la Coupe du Monde, des stars de la t\u00e9l\u00e9 et des films, ou encore des personnalit\u00e9s bien connues. <img decoding=\"async\" class=\"alignleft size-full wp-image-1077 lazyload\" title=\"shirt\" data-src=\"http:\/\/achat.suisse-blog.ch\/wp-content\/uploads\/2010\/06\/shirt.jpg\" alt=\"shirt\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/>Dans cette derni\u00e8re cat\u00e9gorie, vous y trouverez entre autres le tr\u00e8s c\u00e9l\u00e8bre Barak Obama, Dr. House, Jimmy Hendrix, Jim Morrison, Bruce Lee, Gandhi, Nelson Mandela et Bill Murray. Outre le design, vous pouvez aussi y faire ajouter un texte de votre choix. Bref, votre t-shirt sera vraiment personnalis\u00e9 \u00e0 votre go\u00fbt.<\/p>\n<p>Shirtcity vous offre \u00e9galement l\u2019opportunit\u00e9 d\u2019ouvrir gratuitement votre propre boutique, et ce, sans aucun engagement. Gr\u00e2ce \u00e0 ce concept, vous pourrez vendre vos produis personnalis\u00e9s \u00e0 l\u2019effigie de votre design. Pour ce faire, il suffit tout d\u2019abord de vous enregistrer, puis de t\u00e9l\u00e9charger vos motifs, et de cr\u00e9er ensuite vos propres produits par une combinaison de designs et d\u2019articles. Par la suite, il ne vous reste qu\u2019\u00e0 d\u00e9terminer les prix et la marge de profit, de publier le lien ou le sous-domaine, et le tour est jou\u00e9. Pour de plus amples informations, faites un petit d\u00e9tour par le site shirtcity.com.<\/p>\n<p><a href=\"http:\/\/clk.tradedoubler.com\/click?p=61717&#038;a=1401567&#038;g=16974168\" target=\"_BLANK\" rel=\"noopener\"><img decoding=\"async\" src=\"http:\/\/impch.tradedoubler.com\/imp?type(img)g(16974168)a(1401567)\" border=\"0\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Avec Shirtcity, vous pouvez cr\u00e9er votre propre t-shirt personnalis\u00e9 en y ajoutant votre photo, ou en faisant votre choix parmi une vaste gamme de motifs. En effet, peu importe le style que vous adoptez, vous y trouverez assur\u00e9ment un design qui vous plaira gr\u00e2ce aux quelque 1500 motifs propos\u00e9s par Shirtcity. R\u00e9pertori\u00e9s par cat\u00e9gories, les&#8230;<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9,12],"tags":[1102,281,1101,1074,1100,857],"class_list":["post-1075","post","type-post","status-publish","format-standard","hentry","category-cadeaux","category-divers-produits-en-ligne","tag-creation-boutique","tag-design","tag-motifs","tag-objets-personnalises","tag-shirtcity","tag-t-shirt"],"views":701,"taxonomy_info":{"category":[{"value":9,"label":"Cadeaux"},{"value":12,"label":"Divers produits en Ligne"}],"post_tag":[{"value":1102,"label":"cr\u00e9ation boutique"},{"value":281,"label":"design"},{"value":1101,"label":"motifs"},{"value":1074,"label":"objets personnalis\u00e9s"},{"value":1100,"label":"shirtcity"},{"value":857,"label":"T-shirt"}]},"featured_image_src_large":false,"author_info":{"display_name":"Missie","author_link":"https:\/\/achat.suisse-blog.ch\/de\/author\/missie\/"},"comment_info":0,"category_info":[{"term_id":9,"name":"Cadeaux","slug":"cadeaux","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":20,"count":22,"filter":"raw","cat_ID":9,"category_count":22,"category_description":"","cat_name":"Cadeaux","category_nicename":"cadeaux","category_parent":20},{"term_id":12,"name":"Divers produits en Ligne","slug":"divers-produits-en-ligne","term_group":0,"term_taxonomy_id":12,"taxonomy":"category","description":"","parent":1,"count":14,"filter":"raw","cat_ID":12,"category_count":14,"category_description":"","cat_name":"Divers produits en Ligne","category_nicename":"divers-produits-en-ligne","category_parent":1}],"tag_info":[{"term_id":1102,"name":"cr\u00e9ation boutique","slug":"creation-boutique","term_group":0,"term_taxonomy_id":1131,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":281,"name":"design","slug":"design","term_group":0,"term_taxonomy_id":287,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw"},{"term_id":1101,"name":"motifs","slug":"motifs","term_group":0,"term_taxonomy_id":1130,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":1074,"name":"objets personnalis\u00e9s","slug":"objets-personnalises","term_group":0,"term_taxonomy_id":1103,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":1100,"name":"shirtcity","slug":"shirtcity","term_group":0,"term_taxonomy_id":1129,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":857,"name":"T-shirt","slug":"t-shirt","term_group":0,"term_taxonomy_id":881,"taxonomy":"post_tag","description":"","parent":0,"count":7,"filter":"raw"}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":5,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"predecessor-version":[{"id":1246,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1075\/revisions\/1246"}],"wp:attachment":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}