{"id":1082,"date":"2010-06-24T16:06:34","date_gmt":"2010-06-24T14:06:34","guid":{"rendered":"http:\/\/achat.suisse-blog.ch\/?p=1082"},"modified":"2010-08-09T16:48:52","modified_gmt":"2010-08-09T14:48:52","slug":"citydisc-ch-vous-offre-la-livraison-sans-frais-de-port","status":"publish","type":"post","link":"https:\/\/achat.suisse-blog.ch\/de\/1082\/citydisc-ch-vous-offre-la-livraison-sans-frais-de-port\/","title":{"rendered":"Citydisc.ch vous offre la livraison sans frais de port"},"content":{"rendered":"<p>Avec plus de 2 millions de CD, de DVD, de livres et de jeux, citydisc.ch se positionne au premier rang des boutiques en ligne de la Suisse. La section musique comporte bien s\u00fbr des tonnes de CD, r\u00e9pertori\u00e9s par genres, incluant les CD les plus populaires de l\u2019heure et ceux \u00e0 venir prochainement. La plupart d\u2019entre eux sont accompagn\u00e9s d\u2019extraits audio d\u2019une trentaine de secondes. Du c\u00f4t\u00e9 des DVD, vous y retrouverez encore une fois un vaste choix de films, \u00e9galement classifi\u00e9s par genres, ainsi que le top nouveaut\u00e9, les prochaines sorties, les s\u00e9ries de t\u00e9l\u00e9, et les meilleures ventes de DVD. <img decoding=\"async\" class=\"alignleft size-full wp-image-1084 lazyload\" title=\"disque\" data-src=\"http:\/\/achat.suisse-blog.ch\/wp-content\/uploads\/2010\/06\/disque.jpg\" alt=\"disque\" width=\"150\" height=\"150\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/>Quant aux jeux vid\u00e9o, il en existe pour toutes les consoles possibles, allant de la PS2 et PS3, jusqu\u2019\u00e0 la Wii et la xBox 360. D\u2019ailleurs, parlant de consoles, celles-ci y sont \u00e9galement vendues, et pour celles dont la sortie est pr\u00e9vue est pr\u00e9vue prochainement, citydisc.ch vous propose d\u2019en faire la r\u00e9servation. Des puzzles et des jeux en tout genre viennent compl\u00e9ter la section divertissement.<\/p>\n<p><a href=\"http:\/\/clk.tradedoubler.com\/click?p=23681&#038;a=1401567&#038;g=17788594\" target=\"_BLANK\" rel=\"noopener\"><img decoding=\"async\" src=\"http:\/\/impch.tradedoubler.com\/imp?type(img)g(17788594)a(1401567)\" border=\"0\"><\/a><\/p>\n<p>Citydisc.ch ne se limite pas seulement \u00e0 la vente de jeux, de films et de CD, puisqu\u2019on y retrouve \u00e9galement des logiciels de comptabilit\u00e9, Windows 7, et des antivirus, tels que Norton, McAfee, et Kaspersky. On y propose aussi des cl\u00e9s USB, des souris, des claviers, des calculatrices, des traducteurs, des disques vierges, ainsi que des accessoires pour les PC, les iPhone et les iPad. En outre, pour tous les achats que vous effectuerez chez citydisc.ch, vous serez cr\u00e9dit\u00e9 de webmiles, lesquels sont \u00e9changeables contre des primes exclusives.<\/p>\n<p><script type=\"text\/javascript\" src=\"http:\/\/impch.tradedoubler.com\/imp?g(18040152)a(1401567)\" charset=\"ISO-8859-1\"><\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>Avec plus de 2 millions de CD, de DVD, de livres et de jeux, citydisc.ch se positionne au premier rang des boutiques en ligne de la Suisse. La section musique comporte bien s\u00fbr des tonnes de CD, r\u00e9pertori\u00e9s par genres, incluant les CD les plus populaires de l\u2019heure et ceux \u00e0 venir prochainement. La plupart&#8230;<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9,24],"tags":[1186,200,218,253,1189,370,488],"class_list":["post-1082","post","type-post","status-publish","format-standard","hentry","category-cadeaux","category-musique","tag-cadeaux","tag-cd","tag-citydisk","tag-consoles","tag-dvd","tag-films","tag-jeux-videos"],"views":2402,"taxonomy_info":{"category":[{"value":9,"label":"Cadeaux"},{"value":24,"label":"Musique"}],"post_tag":[{"value":1186,"label":"Cadeaux"},{"value":200,"label":"cd"},{"value":218,"label":"citydisk"},{"value":253,"label":"consoles"},{"value":1189,"label":"DVD"},{"value":370,"label":"films"},{"value":488,"label":"jeux vid\u00e9os"}]},"featured_image_src_large":false,"author_info":{"display_name":"Missie","author_link":"https:\/\/achat.suisse-blog.ch\/de\/author\/missie\/"},"comment_info":0,"category_info":[{"term_id":9,"name":"Cadeaux","slug":"cadeaux","term_group":0,"term_taxonomy_id":9,"taxonomy":"category","description":"","parent":20,"count":22,"filter":"raw","cat_ID":9,"category_count":22,"category_description":"","cat_name":"Cadeaux","category_nicename":"cadeaux","category_parent":20},{"term_id":24,"name":"Musique","slug":"musique","term_group":0,"term_taxonomy_id":24,"taxonomy":"category","description":"","parent":30,"count":6,"filter":"raw","cat_ID":24,"category_count":6,"category_description":"","cat_name":"Musique","category_nicename":"musique","category_parent":30}],"tag_info":[{"term_id":1186,"name":"Cadeaux","slug":"cadeaux","term_group":0,"term_taxonomy_id":189,"taxonomy":"post_tag","description":"","parent":0,"count":36,"filter":"raw"},{"term_id":200,"name":"cd","slug":"cd","term_group":0,"term_taxonomy_id":204,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw"},{"term_id":218,"name":"citydisk","slug":"citydisk","term_group":0,"term_taxonomy_id":222,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":253,"name":"consoles","slug":"consoles","term_group":0,"term_taxonomy_id":257,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":1189,"name":"DVD","slug":"dvd","term_group":0,"term_taxonomy_id":310,"taxonomy":"post_tag","description":"","parent":0,"count":17,"filter":"raw"},{"term_id":370,"name":"films","slug":"films","term_group":0,"term_taxonomy_id":378,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"},{"term_id":488,"name":"jeux vid\u00e9os","slug":"jeux-videos","term_group":0,"term_taxonomy_id":501,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/comments?post=1082"}],"version-history":[{"count":4,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1082\/revisions"}],"predecessor-version":[{"id":1244,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/1082\/revisions\/1244"}],"wp:attachment":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/media?parent=1082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/categories?post=1082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/tags?post=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}