{"id":71,"date":"2007-09-25T23:34:00","date_gmt":"2007-09-25T23:34:00","guid":{"rendered":"http:\/\/achat.suisse-blog.ch\/?p=71"},"modified":"2007-09-25T23:34:00","modified_gmt":"2007-09-25T23:34:00","slug":"air-france-et-klm-augmentent-leur-surcharge-carburant-de-1-a-5-euros","status":"publish","type":"post","link":"https:\/\/achat.suisse-blog.ch\/de\/71\/air-france-et-klm-augmentent-leur-surcharge-carburant-de-1-a-5-euros\/","title":{"rendered":"Air France et KLM augmentent leur surcharge carburant de 1 \u00e0 5 euros"},"content":{"rendered":"<p>La compagnie a\u00e9rienne Air France a d\u00e9cid\u00e9 d&rsquo;augmenter sa surcharge carburant par aller et retour d&rsquo;un euro pour ses vols court et moyen-courriers et de 5 euros sur ses vols long-courriers, \u00ab\u00a0en raison du niveau \u00e9lev\u00e9 des cours du p\u00e9trole\u00a0\u00bb, a-t-elle annonc\u00e9 dans un communiqu\u00e9.<\/p>\n<p>Pour la m\u00eame raison, la compagnie a\u00e9rienne KLM va \u00e9galement augmenter ses surcharges carburant de 1 euro sur les billets europ\u00e9ens et de 5 euros sur les billets intercontinentaux, achet\u00e9s aux Pays-Bas.<\/p>\n<p>Au total, la surcharge carburant s&rsquo;\u00e9l\u00e8ve donc \u00e0 25 euros pour les vols europ\u00e9ens et 70 euros pour les autres vols, pr\u00e9cise KLM.<\/p>\n<p>Sur le New York Mercantile Exchange (Nymex), le baril de \u00ab\u00a0light sweet crude\u00a0\u00bb pour livraison en novembre a cl\u00f4tur\u00e9 lundi en baisse de 67 cents \u00e0 80,95 dollars.<\/p>","protected":false},"excerpt":{"rendered":"<p>La compagnie a\u00e9rienne Air France a d\u00e9cid\u00e9 d&rsquo;augmenter sa surcharge carburant par aller et retour d&rsquo;un euro pour ses vols court et moyen-courriers et de 5 euros sur ses vols long-courriers, \u00ab\u00a0en raison du niveau \u00e9lev\u00e9 des cours du p\u00e9trole\u00a0\u00bb, a-t-elle annonc\u00e9 dans un communiqu\u00e9. Pour la m\u00eame raison, la compagnie a\u00e9rienne KLM va \u00e9galement&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[34],"tags":[67,147,194,232,353,501,673,944,948],"class_list":["post-71","post","type-post","status-publish","format-standard","hentry","category-vacances-voyages","tag-air-france","tag-billet-davion","tag-carburant","tag-compagnie-aerienne","tag-euros","tag-klm","tag-petrole","tag-vol","tag-voyages"],"views":244,"taxonomy_info":{"category":[{"value":34,"label":"Vacances voyages"}],"post_tag":[{"value":67,"label":"Air France"},{"value":147,"label":"Billet davion"},{"value":194,"label":"carburant"},{"value":232,"label":"compagnie a\u00e9rienne"},{"value":353,"label":"euros"},{"value":501,"label":"KLM"},{"value":673,"label":"p\u00e9trole"},{"value":944,"label":"vol"},{"value":948,"label":"voyages"}]},"featured_image_src_large":false,"author_info":{"display_name":"Achat online suisse","author_link":"https:\/\/achat.suisse-blog.ch\/de\/author\/admin\/"},"comment_info":0,"category_info":[{"term_id":34,"name":"Vacances voyages","slug":"vacances-voyages","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":45,"filter":"raw","cat_ID":34,"category_count":45,"category_description":"","cat_name":"Vacances voyages","category_nicename":"vacances-voyages","category_parent":0}],"tag_info":[{"term_id":67,"name":"Air France","slug":"air-france","term_group":0,"term_taxonomy_id":68,"taxonomy":"post_tag","description":"","parent":0,"count":10,"filter":"raw"},{"term_id":147,"name":"Billet davion","slug":"billet-davion","term_group":0,"term_taxonomy_id":148,"taxonomy":"post_tag","description":"","parent":0,"count":12,"filter":"raw"},{"term_id":194,"name":"carburant","slug":"carburant","term_group":0,"term_taxonomy_id":198,"taxonomy":"post_tag","description":"","parent":0,"count":2,"filter":"raw"},{"term_id":232,"name":"compagnie a\u00e9rienne","slug":"compagnie-aerienne","term_group":0,"term_taxonomy_id":236,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw"},{"term_id":353,"name":"euros","slug":"euros","term_group":0,"term_taxonomy_id":361,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":501,"name":"KLM","slug":"klm","term_group":0,"term_taxonomy_id":514,"taxonomy":"post_tag","description":"","parent":0,"count":6,"filter":"raw"},{"term_id":673,"name":"p\u00e9trole","slug":"petrole","term_group":0,"term_taxonomy_id":692,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":944,"name":"vol","slug":"vol","term_group":0,"term_taxonomy_id":969,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw"},{"term_id":948,"name":"voyages","slug":"voyages","term_group":0,"term_taxonomy_id":973,"taxonomy":"post_tag","description":"","parent":0,"count":15,"filter":"raw"}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":0,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/posts\/71\/revisions"}],"wp:attachment":[{"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/media?parent=71"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/categories?post=71"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/achat.suisse-blog.ch\/de\/wp-json\/wp\/v2\/tags?post=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}